{"id":2,"name":"Holger","url":"","description":"","link":"https:\/\/www.sankt-josef-es.de\/wpstes\/author\/holger\/","slug":"holger","meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/www.sankt-josef-es.de\/wpstes\/wp-json\/wp\/v2\/users\/2","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sankt-josef-es.de\/wpstes\/wp-json\/wp\/v2\/users"}]}}