{"id":4661,"date":"2020-03-20T19:24:17","date_gmt":"2020-03-20T18:24:17","guid":{"rendered":"https:\/\/www.sankt-josef-es.de\/wpstes\/?p=4661"},"modified":"2026-04-26T16:51:41","modified_gmt":"2026-04-26T14:51:41","slug":"engpaesse-an-blutkonserven-geht-blutspenden","status":"publish","type":"post","link":"https:\/\/www.sankt-josef-es.de\/wpstes\/2020\/03\/20\/engpaesse-an-blutkonserven-geht-blutspenden\/","title":{"rendered":"Engp\u00e4sse an Blutkonserven &#8211; geht Blutspenden!"},"content":{"rendered":"<div><span id=\"fbPhotoSnowliftCaption\" class=\"fbPhotosPhotoCaption\" tabindex=\"0\" aria-live=\"polite\" data-ft=\"{&quot;tn&quot;:&quot;K&quot;}\"><span class=\"hasCaption\">Auch die Katholische Kirche Esslingen bittet alle zu pr\u00fcfen, ob sie in den n\u00e4chsten Tagen und Wochen nicht ein wenig Zeit und Mut aufwenden um Blutspenden zu gehen.<br \/>\nSchon jetzt ein herzliches Dankesch\u00f6n.<\/span><\/span><\/div>\n<div>\n<span class=\"fbPhotosPhotoCaption\" tabindex=\"0\" aria-live=\"polite\" data-ft=\"{&quot;tn&quot;:&quot;K&quot;}\"><span class=\"hasCaption\">Die Corona-Krise trifft die Blutbanken in den Krankenh\u00e4usern, da weniger Menschen zum Blut spenden gehen. Dabei ist es wichtig, dass auch weiterhin regelm\u00e4\u00dfig gespendet wird. Denn: Blutspenden halten nur 42 Tage, danach m\u00fcssen sie entsorgt werden. Besonders Menschen mit schweren akuten und chronischen Krankheiten, wie beispielsweise Krebspatienten, ben\u00f6tigen die Blutpr\u00e4parate. Dazu kommen Unf\u00e4lle, Notfalloperationen und Transplantationen. Bei den Spendeterminen gelten erweiterte Vorsichtsma\u00dfnahmen, so dass niemand ein erh\u00f6htes Ansteckungsrisiko bef\u00fcrchten muss.<br \/>\n<a class=\"_58cn\" href=\"https:\/\/www.facebook.com\/hashtag\/f%C3%BCreinanderdasein?epa=HASHTAG\" target=\"_blank\" rel=\"noopener noreferrer\" data-ft=\"{&quot;type&quot;:104,&quot;tn&quot;:&quot;*N&quot;}\">#f\u00fcreinanderDasein<\/a> <a class=\"_58cn\" href=\"https:\/\/www.facebook.com\/hashtag\/zusammenhalten?epa=HASHTAG\" target=\"_blank\" rel=\"noopener noreferrer\" data-ft=\"{&quot;type&quot;:104,&quot;tn&quot;:&quot;*N&quot;}\">#zusammenhalten<\/a> <a class=\"_58cn\" href=\"https:\/\/www.facebook.com\/hashtag\/blutspenden?epa=HASHTAG\" target=\"_blank\" rel=\"noopener noreferrer\" data-ft=\"{&quot;type&quot;:104,&quot;tn&quot;:&quot;*N&quot;}\">#blutspenden<\/a><\/span><\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span class=\"fbPhotosPhotoCaption\" tabindex=\"0\" aria-live=\"polite\" data-ft=\"{&quot;tn&quot;:&quot;K&quot;}\"><span class=\"hasCaption\"><a href=\"http:\/\/www.blutspende.de\/blutspendetermine\" target=\"_blank\" rel=\"nofollow noopener noreferrer\" data-lynx-mode=\"asynclazy\" data-lynx-uri=\"https:\/\/l.facebook.com\/l.php?u=http%3A%2F%2Fwww.blutspende.de%2Fblutspendetermine%3Ffbclid%3DIwAR3Sr2yuPFw8AfZ8qaW72UJ7GD6n27HLXQrUqyjRoDMJgoGBds-rVzjE8sk&amp;h=AT1xFyNHGsUJ0crqN_u-XkY5ToKkssKHAM1ydT9MevUPhNBp5L0kTf1Aib7EYynMujtMKUcAnVj15tqYPlGohGXd6rA8ey7G9YW4sNgg11zLe9X1CfHAjAyw0goJHqZ0eNigWnE\">www.blutspende.de\/<wbr \/>blutspendetermine<\/a> <\/span><\/span><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Auch die Katholische Kirche Esslingen bittet alle zu pr\u00fcfen, ob sie in den n\u00e4chsten Tagen und Wochen nicht ein wenig Zeit und Mut aufwenden um Blutspenden zu gehen. Schon jetzt ein herzliches Dankesch\u00f6n. Die Corona-Krise trifft die Blutbanken in den<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"iawp_total_views":0,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-4661","post","type-post","status-publish","format-standard","hentry","category-allgemein"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-07-22 08:04:38","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.sankt-josef-es.de\/wpstes\/wp-json\/wp\/v2\/posts\/4661","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sankt-josef-es.de\/wpstes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sankt-josef-es.de\/wpstes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sankt-josef-es.de\/wpstes\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sankt-josef-es.de\/wpstes\/wp-json\/wp\/v2\/comments?post=4661"}],"version-history":[{"count":4,"href":"https:\/\/www.sankt-josef-es.de\/wpstes\/wp-json\/wp\/v2\/posts\/4661\/revisions"}],"predecessor-version":[{"id":13480,"href":"https:\/\/www.sankt-josef-es.de\/wpstes\/wp-json\/wp\/v2\/posts\/4661\/revisions\/13480"}],"wp:attachment":[{"href":"https:\/\/www.sankt-josef-es.de\/wpstes\/wp-json\/wp\/v2\/media?parent=4661"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sankt-josef-es.de\/wpstes\/wp-json\/wp\/v2\/categories?post=4661"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sankt-josef-es.de\/wpstes\/wp-json\/wp\/v2\/tags?post=4661"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}