{"id":803,"date":"2016-12-31T17:19:08","date_gmt":"2016-12-31T16:19:08","guid":{"rendered":"http:\/\/www.sankt-josef-es.de\/wpstes\/?page_id=803"},"modified":"2016-12-31T19:16:45","modified_gmt":"2016-12-31T18:16:45","slug":"lichtraum-5","status":"publish","type":"page","link":"https:\/\/www.sankt-josef-es.de\/wpstes\/wir-ueber-uns\/kirche\/das-auferstehungsfenster\/lichtraum-5\/","title":{"rendered":"Lichtraum 5"},"content":{"rendered":"<p>\n\tIch war erst k&uuml;rzlich in Istanbul und habe unter anderem die blaue Moschee besucht. Seit diesem Erlebnis gef&auml;llt mir das blaue Fenster sehr. Es wirkt auf mich verbindend mit anderen V&ouml;lkern.\n<\/p>\n<p>\n\tIch habe in St. Josef geheiratet, meine Kinder wurden hier getauft, haben Kommunion und Firmung gefeiert, besuchen heute noch regelm&auml;&szlig;ig die Kinderkirche am Hl. Abend &ndash; es ist immer wieder sch&ouml;n, aber der Umbau des Kirchenraumes w&auml;re meiner Meinung nicht notwendig gewesen. Das &bdquo;Vertraute&ldquo; fehlt. Au&szlig;erdem vermisse ich die Maiandacht, die fr&uuml;her dann und wann stattfand. &ndash; 12.05.2013<br \/>\n\t<span style=\"font-size:11px;\"><strong><em>Dorothea Dietrich<\/em><\/strong><\/span>\n<\/p>\n<p>\n\t<u>Josefsfenster<\/u>\n<\/p>\n<table border=\"0\" cellpadding=\"1\" cellspacing=\"1\" style=\"width: 100%;\">\n<tbody>\n<tr>\n<td style=\"width: 100px;\">\n\t\t\t\tJosef:\n\t\t\t<\/td>\n<td>\n\t\t\t\tder Mensch, mit dem wir auch uns identifizieren: erdfarben, irdisch. Geschlossene Augen: im Traum.\n\t\t\t<\/td>\n<\/tr>\n<tr>\n<td>\n\t\t\t\tEngel:\n\t\t\t<\/td>\n<td>\n\t\t\t\twei&szlig;, Licht &ndash; g&ouml;ttliches Licht &ndash; durchscheinend\n\t\t\t<\/td>\n<\/tr>\n<tr>\n<td>\n\t\t\t\tDie Geste:\n\t\t\t<\/td>\n<td>\n\t\t\t\tder Engel wendet sich ihm zu.\n\t\t\t<\/td>\n<\/tr>\n<tr>\n<td>\n\t\t\t\tDer Kreis:\n\t\t\t<\/td>\n<td>\n\t\t\t\tdie g&ouml;ttliche Einheit. In unserem Innersten &ndash; da wo unser Verstand nicht hinkommt &ndash; sind wir mit dem G&ouml;ttlichen verbunden.\n\t\t\t<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>\n\t<u>Altarfenster<\/u>\n<\/p>\n<table border=\"0\" cellpadding=\"1\" cellspacing=\"1\" style=\"width: 100%;\">\n<tbody>\n<tr>\n<td style=\"width: 100px;\">\n\t\t\t\tAufbruch\n\t\t\t<\/td>\n<td>\n\t\t\t\tAlles, was uns einzw&auml;ngt, fesselt (oft auch die Tradition), ist zerbrochen. Das G&ouml;ttliche w&auml;chst weit &uuml;ber unsere Vorstellungen hinaus. Die st&auml;ndig wechselnden Lichtreflexe sind geradezu ein Symbol f&uuml;r das Unfassbare.\n\t\t\t<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>\n\tEs ist ein Bild der Sehnsucht nach dem Ewigen, ein Bild gro&szlig;er Hoffnung.<br \/>\n\t<span style=\"font-size:11px;\"><em><strong>M. Gerstl-Bonmassar<\/strong><\/em><\/span>\n<\/p>\n<p>\n\t<u>Auferstehungsfenster<\/u><br \/>\n\t<a href=\"https:\/\/www.sankt-josef-es.de\/wpstes\/wp-content\/uploads\/Kirche\/Lichtraum\/lichtraum05.jpg\" target=\"_blank\"><img decoding=\"async\" alt=\"\" src=\"https:\/\/www.sankt-josef-es.de\/wpstes\/wp-content\/uploads\/Kirche\/Lichtraum\/lichtraum05.jpg\" style=\"margin-right: 10px; width: 250px; height: 167px; float: left;\" \/><\/a>Ich sehe ein Kreuz, ein menschliches Kreuz, die Arme hoch erhoben, sich &ouml;ffnend, sich verbindend im \/( mit dem Rund. Ich sehe Splitter \/ Dornen, schmerzende, die aber sich einf&uuml;gen in das Wundergeschehen der Wandlung. Ich sehe das sich brechende Brot (Hostie), das sich weitergeben will.\n<\/p>\n<p>\n\tIch bin eingetaucht in ein transzendentales Geschehen (blau), das in Licht (wei&szlig;) taucht, vielleicht endet. Ich bewege mich in verschiedenen Schichten, Tiefen. Je nachdem. Es ist eine Einladung ohne jegliches Muss.\n<\/p>\n<p>\n\t<u>Josefsfenster<\/u><br \/>\n\tIch sehe im Rund 2 Gestalten, eine nahezu gesichtslose Engelgestalt, die ihre Hand segnend \/ ber&uuml;hrend ausstreckt, und eine kr&auml;ftige M&auml;nnergestalt, Josef, zusammengesackt. Ich bleibe an Josef h&auml;ngen, seiner Leere, seiner Einsamkeit, seinen Schmerzen. Ich sehe keine &Ouml;ffnung.\n<\/p>\n<p>\n\tDer Raum zwischen Engel und Josef, das lebendige tiefe und erdige Gr&uuml;n, l&auml;sst hoffen, ebenso der fast menschliche Engel in seiner Liebe.\n<\/p>\n<p>\n\tMit tut das bewegte, lebendige Blau-Gr&uuml;n-Violett im Hintergrund gut.<br \/>\n\t<span style=\"font-size:11px;\"><em><strong>Unbekannt<\/strong><\/em><\/span>\n<\/p>\n<p>\n\tDas hintere Fenster Josef und der Engel eine wunderbare Harmonie. Josef, der H&ouml;rende. Danach nimmt er die Maria in seinen Schutz.\n<\/p>\n<p>\n\tIm Altarraum das sogenannte Auferstehungsfenster sagt mir gar nichts. Es ist verwirrend.\n<\/p>\n<p>\n\tFreude (<em>gemeint sind wohl Freu<\/em><em><strong>n<\/strong><\/em><em>de<\/em>), die in St. Josef zuhause waren, kommen nicht mehr, da sie mit dem Auferstehungsfenster nichts anfangen k&ouml;nnen. Sie gehen in eine andere Kirche. Sind aber sehr gl&auml;ubig sind in Kolping zu Hause.<br \/>\n\t<span style=\"font-size:11px;\"><em><strong>Unbekannt<\/strong><\/em><\/span>\n<\/p>\n<p>\n\t<u>Auferstehungsfenster:<\/u>\n<\/p>\n<ul>\n<li>\n\t\tAuf den ersten Blick ein Kreuz in blauem Kreis\n\t<\/li>\n<li>\n\t\tKraft, St&auml;rke durch den von unten nach oben dicker werdenden Kreuzstamm.\n\t<\/li>\n<li>\n\t\tDynamik, Bewegung durch die Asymmetrie\n\t<\/li>\n<li>\n\t\tTrotzdem wird das alles durch den blauen Kreis &bdquo;im Zaum&ldquo; gehalten, bekommt eine gewisse Ordnung.\n\t<\/li>\n<li>\n\t\tDas Kreuz &bdquo;&ouml;ffnet&ldquo; den blauen Kreis nach au&szlig;en bzw. dringt in die Ordnung ein\n\t<\/li>\n<li>\n\t\tDie kleineren wei&szlig;en Striche stehen f&uuml;r mich als &bdquo;Blitze&ldquo; f&uuml;r die Unw&auml;gbarkeiten des Lebens. Sie attackieren das Kreuz, bringen den Glauben ins Wanken, st&uuml;tzen das Kreuz aber auch (links und rechts)\n\t<\/li>\n<li>\n\t\tDas Fenster gibt Hoffnung und Kraft.\n\t<\/li>\n<\/ul>\n<p>\n\t<u>Josefsfenster<\/u>\n<\/p>\n<ul>\n<li>\n\t\tLicht in der Dunkelheit, es n&auml;hert sich uns, will uns ber&uuml;hren und aufwecken &ndash; das &bdquo;uns&ldquo; symbolisiert durch den sitzenden Menschen rechts.\n\t<\/li>\n<li>\n\t\tDer Mensch rechts wirkt auf mich ermattet, ersch&ouml;pft, obwohl auf den ersten Blick kr&auml;ftiger und gr&ouml;&szlig;er als die gesichtslose Person links\n\t<\/li>\n<li>\n\t\tLetztere n&auml;hert sich sanft und behutsam, fast sch&uuml;chtern\n\t<\/li>\n<li>\n\t\tDas Fenster strahlt auf mich Ruhe aus.\n\t<\/li>\n<\/ul>\n<p>\n\t<span style=\"font-size:11px;\"><em><strong>Unbekannt<\/strong><\/em><\/span>\n<\/p>\n<p>\n\t<a href=\"https:\/\/www.sankt-josef-es.de\/wpstes\/wir-ueber-uns\/kirche\/das-auferstehungsfenster\/lichtraum-4\/\"><u><span style=\"font-size:12px;\"><strong><em>&lt;&lt; vorige Seite<\/em><\/strong><\/span><\/u><\/a>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ich war erst k&uuml;rzlich in Istanbul und habe unter anderem die blaue Moschee besucht. Seit diesem Erlebnis gef&auml;llt mir das blaue Fenster sehr. Es wirkt auf mich verbindend mit anderen V&ouml;lkern. Ich habe in St. Josef geheiratet, meine Kinder wurden<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":369,"menu_order":4,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"iawp_total_views":0,"footnotes":""},"class_list":["post-803","page","type-page","status-publish","hentry"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 14:43:15","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.sankt-josef-es.de\/wpstes\/wp-json\/wp\/v2\/pages\/803","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sankt-josef-es.de\/wpstes\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.sankt-josef-es.de\/wpstes\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.sankt-josef-es.de\/wpstes\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sankt-josef-es.de\/wpstes\/wp-json\/wp\/v2\/comments?post=803"}],"version-history":[{"count":14,"href":"https:\/\/www.sankt-josef-es.de\/wpstes\/wp-json\/wp\/v2\/pages\/803\/revisions"}],"predecessor-version":[{"id":858,"href":"https:\/\/www.sankt-josef-es.de\/wpstes\/wp-json\/wp\/v2\/pages\/803\/revisions\/858"}],"up":[{"embeddable":true,"href":"https:\/\/www.sankt-josef-es.de\/wpstes\/wp-json\/wp\/v2\/pages\/369"}],"wp:attachment":[{"href":"https:\/\/www.sankt-josef-es.de\/wpstes\/wp-json\/wp\/v2\/media?parent=803"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}