{"id":590,"date":"2016-12-04T18:16:14","date_gmt":"2016-12-04T17:16:14","guid":{"rendered":"http:\/\/www.sankt-josef-es.de\/wpstes\/?page_id=590"},"modified":"2016-12-31T18:21:16","modified_gmt":"2016-12-31T17:21:16","slug":"versoehnung-beichte","status":"publish","type":"page","link":"https:\/\/www.sankt-josef-es.de\/wpstes\/lebenswendepunkte\/versoehnung-beichte\/","title":{"rendered":"Vers\u00f6hnung \/ Beichte"},"content":{"rendered":"<p>\n\t<span style=\"font-size:14px;\"><em>&bdquo;Ja, Gott war es, der in Christus<br \/>\n\tdie Welt mit sich vers&ouml;hnt hat, indem<br \/>\n\ter den Menschen ihre Verfehlungen<br \/>\n\tnicht anrechnete und uns das Wort<br \/>\n\tvon der Vers&ouml;hnung anvertraute.<br \/>\n\tWir sind also Gesandte an Christi Statt,<br \/>\n\tund Gott ist es, der durch uns mahnt.<br \/>\n\tWir bitten an Christi Statt:<br \/>\n\tLasst euch mit Gott vers&ouml;hnen!&ldquo;<br \/>\n\t(2 Kor 5,19-2 0)<\/em><\/span>\n<\/p>\n<p>\n\t<strong>Das Sakrament der Beichte<\/strong><br \/>\n\tDie Beichte ist das Sakrament der Zuwendung Gottes gerade in unseren Fehlern und S&uuml;nden. Gott wagt mit einem jeden von uns einen Neubeginn, der ihm seine S&uuml;nden anvertraut und den inneren Willen besitzt sich zu Erneuern.\n<\/p>\n<p>\n\tZu diesem Gespr&auml;ch mit einem Priester laden wir Sie herzlich ein.\n<\/p>\n<p>\n\tBeichtgelegenheit gibt es w&ouml;chentlich<br \/>\n\t<strong>Samstags, 16.30 Uhr &ndash; 17.30 Uhr im M&uuml;nster St. Paul\/ Innenstadt<br \/>\n\toder Sie nehmen direkt mit einem unserer Priester Kontakt auf.<\/strong>\n<\/p>\n<p>\n\tEin kleiner Clip zum Thema Beichte <a href=\"http:\/\/www.katholisch.de\/de\/katholisch\/video\/video_details.php?id=1258\" target=\"_blank\"><u>hier<\/u><\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&bdquo;Ja, Gott war es, der in Christus die Welt mit sich vers&ouml;hnt hat, indem er den Menschen ihre Verfehlungen nicht anrechnete und uns das Wort von der Vers&ouml;hnung anvertraute. Wir sind also Gesandte an Christi Statt, und Gott ist es,<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":575,"menu_order":7,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"iawp_total_views":0,"footnotes":""},"class_list":["post-590","page","type-page","status-publish","hentry"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 14:10:53","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.sankt-josef-es.de\/wpstes\/wp-json\/wp\/v2\/pages\/590","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sankt-josef-es.de\/wpstes\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.sankt-josef-es.de\/wpstes\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.sankt-josef-es.de\/wpstes\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sankt-josef-es.de\/wpstes\/wp-json\/wp\/v2\/comments?post=590"}],"version-history":[{"count":2,"href":"https:\/\/www.sankt-josef-es.de\/wpstes\/wp-json\/wp\/v2\/pages\/590\/revisions"}],"predecessor-version":[{"id":621,"href":"https:\/\/www.sankt-josef-es.de\/wpstes\/wp-json\/wp\/v2\/pages\/590\/revisions\/621"}],"up":[{"embeddable":true,"href":"https:\/\/www.sankt-josef-es.de\/wpstes\/wp-json\/wp\/v2\/pages\/575"}],"wp:attachment":[{"href":"https:\/\/www.sankt-josef-es.de\/wpstes\/wp-json\/wp\/v2\/media?parent=590"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}